{"id":1652,"date":"2022-03-04T16:44:55","date_gmt":"2022-03-04T21:44:55","guid":{"rendered":"https:\/\/cerosetenta.uniandes.edu.co\/las-derechas\/?p=1652"},"modified":"2022-03-30T16:59:38","modified_gmt":"2022-03-30T21:59:38","slug":"chile","status":"publish","type":"post","link":"https:\/\/jaqueala.com\/lasderechas\/pt\/chile\/","title":{"rendered":"Chile"},"content":{"rendered":"<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Em estado de choque, assim ficou grande parte da direita chilena ap\u00f3s os resultados do plebiscito constitucional de 25 de outubro no Chile, que teve como ganhadora a op\u00e7\u00e3o do \u201cAprovo\u201d para uma Nova Constitui\u00e7\u00e3o, com 78% das prefer\u00eancias. O \u201cRejeito\u201d, op\u00e7\u00e3o levantada principalmente pela coaliz\u00e3o Chile Vamos, que sustenta hoje o abatido governo de Sebasti\u00e1n Pi\u00f1era, ficou marginalizado com 20% dos votos. Enquanto a direita economicista herdeira da Constitui\u00e7\u00e3o de Pinochet chorava a derrota, o mundo \u201csolid\u00e1rio\u201d e mais liberal da direita, que apostou na mudan\u00e7a constitucional, viu vantagem, j\u00e1 que conseguira ganhar a primeira batalha na disputa pela hegemonia da direita chilena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A discuss\u00e3o pela Constituinte aprofundou a disputa ideol\u00f3gica na direita, que se tornou evidente ap\u00f3s a revolta social de outubro de 2019, que inundou as ruas no Chile. A possibilidade de criar uma nova Constitui\u00e7\u00e3o tornou p\u00fablico um silencioso debate que acontecia entre as elites intelectuais: mudar o modelo do Estado Subsidi\u00e1rio que regeu o Chile durante os \u00faltimos 30 anos. O racha na direita foi transversal: em todos os partidos do governo houve parlamentares, dirigentes sociais e militantes de base que se dividiram entre o Aprovo e o Rejeito. A Uni\u00e3o Democrata Independente (UDI), partido fundado por Jaime Guzm\u00e1n, ide\u00f3logo da Constitui\u00e7\u00e3o de 1980, foi um dos que liderou o comando do Rejeito, mas sua figura pol\u00edtica com maior apoio cidad\u00e3o e candidato presidencial, o prefeito de Las Condes, Joaqu\u00edn Lav\u00edn, disse publicamente que votaria a favor do Aprovo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O partido Renova\u00e7\u00e3o Nacional (RN), detentor do maior n\u00famero de assentos no Congresso, dividiu-se provocando duros atritos internos entre o setor mais progressista ou \u201csolid\u00e1rio\u201d e o mundo mais conservador e pr\u00f3-mercado. Ev\u00f3poli, o partido mais novo da coaliz\u00e3o, identificado com o mundo mais liberal em seus prim\u00f3rdios, entrou em um loop de contradi\u00e7\u00f5es: primeiro apoiou o \u201cAprovo\u201d, depois mudou para \u201cRejeito\u201d e, posteriormente, deram liberdade de a\u00e7\u00e3o a seus militantes. Apenas o pequeno Partido Regionalista Independente manteve uma postura \u00fanica de apoio ao \u201cAprovo\u201d. O chefe da coaliz\u00e3o, o presidente Sebasti\u00e1n Pi\u00f1era, semeou a d\u00favida at\u00e9 o \u00faltimo momento: nunca tornou p\u00fablica sua postura, embora seu gabinete ministerial tenha estado marcado por ministros e ministras que optaram pelo \u201cRejeito\u201d. Depois do plebiscito, foi informado que sua filha, Magdalena Pi\u00f1era, ser\u00e1 candidata a delegada da Conven\u00e7\u00e3o Constitucional pela Renova\u00e7\u00e3o Nacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Segundo analistas pol\u00edticos e militantes de Chile Vamos, a revolta social de 2019 e o in\u00edcio do processo constituinte marcaram um ponto sem retorno dentro da direita, que est\u00e1 dividida entre a emergente \u201csensibilidade solid\u00e1ria\u201d, como denominado pela soci\u00f3loga St\u00e9phanie Alenda, em seu livro Anatom\u00eda de la derecha chilena, a \u201csensibilidade subsidi\u00e1ria\u201d da direita tradicional, economicista e conservadora, e uma marginal \u201csensibilidade libert\u00e1ria\u201d, que \u00e9 minorit\u00e1ria. Fora do conglomerado governista surge a \u201cdireita dura\u201d que imita o populismo de Donald Trump e Jair Bolsonaro, mas que n\u00e3o conseguiu sair da marginalidade. A pergunta \u00e9: qual desses mundos ou sensibilidades conseguir\u00e1 liderar a direita nos pr\u00f3ximos anos?<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A crise dos economicistas<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A derrota no plebiscito atingiu duramente \u201cLa Casa Com\u00fan del Rechazo\u201d (A Casa Comum do Rejeito), comando que abrigou a direita tradicional chilena, localizado na comuna de Vitacura, onde reside parte importante da elite econ\u00f4mica e pol\u00edtica do pa\u00eds. As bandejas com comida ficaram quase intactas e v\u00e1rios rostos sumiram antes de o deputado Diego Schalper (RN), porta-voz do Rejeito e parte da nova camada de pol\u00edticos da direita, reconhecer que sua posi\u00e7\u00e3o alcan\u00e7ara apenas 20% do apoio dos cidad\u00e3os. Um triste cart\u00e3o postal que, segundo militantes e intelectuais de Chile Vamos, reflete o complexo estado em que vive o n\u00facleo economicista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A tese do Estado Subsidi\u00e1rio e uma pol\u00edtica liberal<\/strong> na esfera econ\u00f4mica, mas conservadora na moral, foi constru\u00edda com base nos pilares da Constitui\u00e7\u00e3o de 1980, inspirada pelo \u201cgremialismo\u201d de Jaime Guzm\u00e1n. Tamb\u00e9m na teoria econ\u00f4mica dos Chicago Boys, um seleto grupo de economistas chilenos da Universidade Cat\u00f3lica, que se especializaram na Universidade de Chicago, sob o influxo das ideias de Milton Friedman, e que converteram o Chile em um experimento \u201cneoliberal\u201d. Nos corredores, os partid\u00e1rios da subsidiariedade reconhecem que ficaram para tr\u00e1s aqueles bons tempos em que, apesar de n\u00e3o serem governo durante 20 anos, conseguiram influenciar a pol\u00edtica p\u00fablica dos mandatos de centro-esquerda, dirigidos pelo Concerta\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o estudo realizado pela soci\u00f3loga St\u00e9phanie Alenda, Anatom\u00eda de la derecha chilena, o setor economicista ou de \u201csensibilidade subsidi\u00e1ria\u201d representa mais da metade dos quadros dirigentes de Chile Vamos e encontra-se presente em todos os seus partidos, com maior presen\u00e7a na UDI.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u201cQuando os dirigentes nos diziam que eram a favor de o Estado implementar pol\u00edticas redistributivas para os grupos vulner\u00e1veis, mas que eram ao mesmo tempo contra o aumento da carga tribut\u00e1ria pessoal para financiar pol\u00edticas do \u00e2mbito da prote\u00e7\u00e3o social, n\u00f3s os classificamos como subsidi\u00e1rios. Uma categoria consagrada na Constitui\u00e7\u00e3o de 80, na qual o papel do Estado fica subordinado ao Mercado e ao setor privado. A Constitui\u00e7\u00e3o outorga um papel residual ou complementar ao Estado, quando o setor privado n\u00e3o consegue assumir\u201d.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Essa direita foi ungida com base em uma estreita rela\u00e7\u00e3o com a <strong>Igreja Cat\u00f3lica<\/strong>, raz\u00e3o pela qual o conservadorismo se imp\u00f5e no \u00e2mbito moral. Com os anos, os setores mais liberais, principalmente ligados a Ev\u00f3polis, ganharam terreno e se abriram para o reconhecimento dos direitos da <strong>diversidade sexual, apoiando iniciativas como o Acordo de Uni\u00e3o Civil e a Lei de Identidade de G\u00eanero,<\/strong> e neste ano o presidente Sebasti\u00e1n Pi\u00f1era apresentar\u00e1 uma Lei do Casamento Igualit\u00e1rio. Avan\u00e7os que n\u00e3o deixam os setores mais religiosos de Chile Vamos, como o evang\u00e9lico, totalmente contentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um obst\u00e1culo chega com <strong>as reivindica\u00e7\u00f5es feministas em mat\u00e9ria reprodutiva, como a legaliza\u00e7\u00e3o do aborto.<\/strong> De acordo com pesquisa realizada pela empresa Cadem em julho de 2020, \u201cLa derecha mira a la derecha\u201d (A direita olha para a direita), 67% dos chilenos que se identificam como de direita n\u00e3o est\u00e3o de acordo com uma Lei de Aborto Liberal. \u201cEu n\u00e3o sou feminista, sou feminina, sou mulher e adoraria que essa op\u00e7\u00e3o fosse respeitada. N\u00e3o acredito no aborto livre, n\u00e3o falo em patriarcado, nem em matriarcado, n\u00e3o acredito que se trate de uma briga com os homens\u201d, enfatizou a presidenta da bancada de deputados\/as da UDI, Pepa Hoffman, em \u201cLa ma\u00f1ana em Chilevisi\u00f3n\u201d, um programa popular da TV matutino, no qual se analisava a massiva marcha do 8 de mar\u00e7o no Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A direita economicista impera no governo do presidente Sebasti\u00e1n Pi\u00f1era, cuja base t\u00e9cnica e de influ\u00eancia pol\u00edtica se resguarda no centro de estudos Liberdade e Desenvolvimento (LyD), fundado por Cristi\u00e1n Larroulet, chefe da equipe de assessores do presidente e uma das poucas pessoas que consegue influenciar o presidente. Esse <em>think tank<\/em> foi tamb\u00e9m o n\u00facleo pol\u00edtico e ideol\u00f3gico do \u201cRejeito\u201d, acolhendo v\u00e1rias figuras que tiveram que deixar o governo ap\u00f3s a revolta social.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full imagen-izquierda\"><img fetchpriority=\"high\" decoding=\"async\" width=\"638\" height=\"660\" src=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png\" alt=\"\" class=\"wp-image-74\" srcset=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png 638w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1-290x300.png 290w\" sizes=\"(max-width: 638px) 100vw, 638px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u201cLiberdade e Desenvolvimento, que se apresenta como um centro de estudos, \u00e9 mais um lugar de tr\u00e1fico de influ\u00eancias e forma\u00e7\u00e3o de quadros. Esses poderes f\u00e1ticos s\u00e3o importantes na direita chilena. At\u00e9 que ponto esse processo e impulso de renova\u00e7\u00e3o ideol\u00f3gica \u00e9 capaz de enfrentar o aparato dos que est\u00e3o realmente convencidos desse discurso economicista? Os que se reproduzem em setores autocontidos, mas seu poder econ\u00f4mico e de influ\u00eancia social nos bastidores \u00e9 muito forte\u201d, destaca Hugo Herrera, fil\u00f3sofo e acad\u00eamico da Universidade Diego Portales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A diretora executiva do <em>think tank<\/em> \u00e9 Marcela Cubillos (UDI), ex-ministra da Educa\u00e7\u00e3o do atual governo e uma das figuras mais controversas e duras da direita tradicional. Cubillos foi implementando um novo estilo comunicacional, muito mais direto e incendi\u00e1rio, baseado nas redes sociais e no impacto no Twitter, muito semelhante ao da \u201cultradireita\u201d que est\u00e1 fora de Chile Vamos. Estilo diferente do da direita tradicional que est\u00e1 acostumada a intervir na esfera p\u00fablica atrav\u00e9s dos meios de comunica\u00e7\u00e3o tradicionais, como o jornal <em>El Mercurio<\/em>, embora tamb\u00e9m tenham usado pesquisas e an\u00e1lises de BigData no segundo governo de Sebasti\u00e1n Pi\u00f1era.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cristi\u00e1n Leporati, especialista em comunica\u00e7\u00e3o pol\u00edtica, destaca que <strong>a direita tradicional \u201ctem um problema, porque a linguagem que costumam usar, e a propaganda mais cl\u00e1ssica de direita funciona em algumas m\u00eddias tradicionais, mas n\u00e3o nas novas m\u00eddias, onde est\u00e3o justamente os p\u00fablicos mais jovens.<\/strong> A direita n\u00e3o conseguiu resolver como operar as redes sociais, n\u00e3o podemos esquecer que <strong>os <em>bots<\/em> <\/strong>(um software preparado para realizar atividades repetitivas) <strong>n\u00e3o votam, geram climas, mas n\u00e3o votam\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre os intelectuais da direita \u00e9 consenso que esse setor, de sensibilidade subsidi\u00e1ria ou economicista, est\u00e1 em crise e que parte da responsabilidade por esse fracasso \u00e9 da lideran\u00e7a exercida pelo presidente Sebasti\u00e1n Pi\u00f1era. A historiadora liberal Valentina de Verbal aponta que a crise do setor teve in\u00edcio em 2011, ano em que Sebasti\u00e1n Pi\u00f1era come\u00e7ou a ceder perante as demandas do Movimento Estudantil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u201cN\u00e3o defendeu os princ\u00edpios da liberdade econ\u00f4mica, o direito de lucrar no mercado, n\u00e3o por raz\u00f5es econ\u00f4micas, mas sim morais, porque a\u00ed est\u00e3o os empreendedores, as pessoas que acordam cedo\u201d, <br><small>diz Verbal.<\/small><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para a autora do livro La Derecha Perdida o presidente foi renunciando ao seu pr\u00f3prio ide\u00e1rio a favor das ideias de esquerda, \u201ctanto que a direita incluiu no programa de \u2018Pi\u00f1era II\u2019 a gratuidade universal nos Institutos T\u00e9cnicos Profissionais, que foi uma medida de Manuel Jos\u00e9 Ossand\u00f3n (ex-candidato presidencial da direita social) para tentar ganhar votos. O atual Estado \u00e9 um Estado de bem-estar, n\u00e3o t\u00e3o extremo quanto o promovido pela esquerda, mas \u00e9 um Estado de bem-estar no final porque tem projetos a favor da classe m\u00e9dia, como o programa Classe M\u00e9dia Protegida\u201d, acrescenta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA verdade \u00e9 que o Chile nunca teve um Estado subsidi\u00e1rio, o Estado no Chile est\u00e1 muito presente em todos os \u00e2mbitos. Pense em todos os minist\u00e9rios que possui, todos os \u00f3rg\u00e3os, para cada problema h\u00e1 um \u00f3rg\u00e3o p\u00fablico que se encarrega desse problema, e isso n\u00e3o \u00e9 pr\u00f3prio de um Estado subsidi\u00e1rio no sentido de subsidiariedade negativa (o estado se abst\u00e9m de agir). Eu considero que o Chile, de modo geral, mesmo com o modelo concebido pelos \u2018Chicago Boys\u2019, avan\u00e7ou para um Estado mais forte\u201d, garante Valentina Verbal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O fil\u00f3sofo Hugo Herrera acredita tamb\u00e9m que o presidente Pi\u00f1era foi um fator-chave na crise que a direita atravessa, mas de uma perspectiva mais social. \u201cPara muitos na direita, o primeiro governo de Pi\u00f1era n\u00e3o deixou legado pol\u00edtico, n\u00e3o foi capaz de transferir o poder para outra pessoa de direita, mas mais do que isso, n\u00e3o houve um discurso pol\u00edtico que pudesse enfrentar a situa\u00e7\u00e3o e conduzi-la\u201d, enfatiza o acad\u00eamico da UDP.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAcredito que o problema de Pi\u00f1era \u00e9 que seu quadro conceitual era muito estreito, e \u00e9 o problema de grande parte da direita.<strong> Ele entende a pol\u00edtica como gest\u00e3o econ\u00f4mica e gest\u00e3o policial.<\/strong> Isso \u00e9 algo que entrou no Chile e \u00e9 estranho entender, mas se vemos os textos de Milton Friedman, e os chilenos que foram estudar economia com Friedman o assumiram completamente, s\u00e3o duas ideias: <strong>que a sociedade \u00e9 um mero agregado e que os indiv\u00edduos funcionam separadamente,<\/strong> e que a ordem econ\u00f4mica liberal \u00e9 a base de uma ordem pol\u00edtica adequada, sob a premissa de que os indiv\u00edduos perseguem seus fins separadamente. Ent\u00e3o,<strong> o povo n\u00e3o existe<\/strong> e vem uma crise como a de 2011 ou a de outubro de 2019, o povo irrompe e Pi\u00f1era n\u00e3o consegue ver bem o que est\u00e1 acontecendo, porque suas categorias conceituais lhe impedem ver, porque n\u00e3o se pode ler a manifesta\u00e7\u00e3o de milh\u00f5es nas ruas a partir da concep\u00e7\u00e3o de indiv\u00edduos que perseguem seus fins separadamente, n\u00e3o tem sentido\u201d, aponta o fil\u00f3sofo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>A irrup\u00e7\u00e3o da direita social<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No ano de 2016, a soci\u00f3loga St\u00e9phanie Alenda come\u00e7ou o estudo Anatom\u00eda de la derecha chilena, publicado como livro em 2020, que inclui 700 lideran\u00e7as da coaliz\u00e3o Chile Vamos. L\u00e1 ela identificou que 30% dos militantes mostravam uma sensibilidade diferente \u00e0 hist\u00f3rica subsidi\u00e1ria e <strong>esperavam um papel social mais ativo do Estado<\/strong>. Ela os definiu como portadores de uma \u201csensibilidade solid\u00e1ria\u201d. \u201cTrata-se de uma posi\u00e7\u00e3o que enfatiza<strong> a relev\u00e2ncia de aumentar os impostos individuais para financiar a prote\u00e7\u00e3o social<\/strong>, o que nos chamou a aten\u00e7\u00e3o. Os solid\u00e1rios aparecem sempre como os mais progressistas quando lhes perguntamos o que opinam sobre aumentar os impostos sobre as grandes empresas ou do lucro na educa\u00e7\u00e3o; tamb\u00e9m sobre assuntos morais, socioculturais. O comportamento desse segmento se mant\u00e9m sempre coerente, confirmando <strong>sua tend\u00eancia \u00e0 modera\u00e7\u00e3o,<\/strong>explica Alenda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa sensibilidade solid\u00e1ria est\u00e1 transversalmente presente em Chile Vamos como um todo, mas se concentra no partido Renova\u00e7\u00e3o Nacional, que \u00e9 mais diverso e com menos controle interno do que a UDI, que incorpora l\u00edderes de uma origem social diferente, principalmente de camadas m\u00e9dias e baixas. Suas lideran\u00e7as tendem a ocupar cargos com uma maior conex\u00e3o territorial; geralmente s\u00e3o prefeitos, vereadores ou parlamentares que n\u00e3o fizeram carreira unicamente com base na pol\u00edtica. Um de seus primeiros precursores \u00e9 o senador Manuel Jos\u00e9 Ossand\u00f3n, que prov\u00e9m de uma fam\u00edlia abastada, latifundi\u00e1ria e muito religiosa, mas cursou seus estudos como t\u00e9cnico agr\u00edcola em um Instituto Profissional e foi prefeito durante 12 anos da comuna de Puente Alto, uma das mais populosas e pobres do Chile. Os mais pr\u00f3ximos dizem que \u201ca rua o levou a desenvolver uma vis\u00e3o mais social-crist\u00e3 da pol\u00edtica\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEm 2014, o Renova\u00e7\u00e3o Nacional faz uma reforma na declara\u00e7\u00e3o de princ\u00edpios quando entra a lideran\u00e7a de Nicol\u00e1s Monckeberg, retiram a alus\u00e3o \u00e0 ditadura e incorporam textos da Democracia Crist\u00e3 alem\u00e3, tentam fazer uma esp\u00e9cie de guinada para uma direita mais europeia. Isso tem outros marcos, como a incorpora\u00e7\u00e3o do RN \u00e0 Internacional Democrata de Centro, onde teve o apoio de Conrad e da DC alem\u00e3. Soma-se a isso todo um trabalho dos centros de estudo, de pessoas mais ligadas ao mundo acad\u00eamico tamb\u00e9m, mas que t\u00eam um p\u00e9 na pol\u00edtica\u201d, explica o fil\u00f3sofo Hugo Herrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse bloco solid\u00e1rio se mostrou em sua m\u00e1xima express\u00e3o ao apoiar a \u201cLei de Aposentadoria de 10% dos Fundos de Pens\u00e3o da AFP\u201d, que pretendia que as pessoas pudessem sacar parte de suas economias previdenci\u00e1rias para pagar os custos da crise econ\u00f4mica, diante da insufici\u00eancia das pol\u00edticas de ajuda do governo de Sebasti\u00e1n Pi\u00f1era. Um projeto que abalou as bases do sistema de seguridade social baseado na capitaliza\u00e7\u00e3o individual e que para o setor economicista da direita significou um ponto sem volta em mat\u00e9ria de liberdade econ\u00f4mica. \u201cDevo votar hoje com consci\u00eancia, por empatia, em consequ\u00eancia com minha hist\u00f3ria de vida. Sei o que \u00e9 ter fome e passar frio\u201d, disse a deputada Erika Olivera (RN) que chegou ao parlamento depois de uma reconhecida carreira como atleta.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-full imagen-izquierda\"><img decoding=\"async\" width=\"827\" height=\"638\" src=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE2.png\" alt=\"\" class=\"wp-image-90\" srcset=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE2.png 827w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE2-300x231.png 300w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE2-768x592.png 768w\" sizes=\"(max-width: 827px) 100vw, 827px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">O principal l\u00edder do setor solid\u00e1rio \u00e9 o ex-presidente do Renova\u00e7\u00e3o Nacional, Mario Desbordes, que deixou seu cargo como deputado h\u00e1 alguns meses para chefiar o Minist\u00e9rio da Defesa do governo de Sebasti\u00e1n Pi\u00f1era. Desbordes tem uma carreira at\u00edpica no mundo da pol\u00edtica chilena: cresceu na comuna de classe m\u00e9dia baixa La Cisterna, foi parte dos Carabineros (a pol\u00edcia civil chilena) e estudou direito e administra\u00e7\u00e3o de empresas em universidades n\u00e3o tradicionais. Somente no ano 2000 passou a militar no RN e participou do primeiro governo de Sebasti\u00e1n Pi\u00f1era. Na campanha para o segundo per\u00edodo de Pi\u00f1era, foi um dos que impulsionou a gratuidade para a educa\u00e7\u00e3o t\u00e9cnico-profissional e o cancelamento das d\u00edvidas do Cr\u00e9dito com Aval do Estado, pol\u00edtica que endividou a quase um milh\u00e3o de jovens para financiar seus estudos superiores.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em meio ao levante social de 2019, destacou-se por ser uma voz dissidente dentro da direita, foi um dos principais articuladores do \u201cAcordo pela Paz e uma Nova Constitui\u00e7\u00e3o\u201d e, em v\u00e1rias ocasi\u00f5es, fez um chamado a <strong>\u201couvir a rua\u201d<\/strong>. Foi um dos primeiros a apoiar o projeto de \u201cAposentadoria de 10%\u201d e liderou o setor do \u201cAprovo\u201d na direita. Sua incorpora\u00e7\u00e3o ao gabinete foi um sinal de governabilidade interna em Chile Vamos, j\u00e1 que se uniu a ele Andr\u00e9 Allamand (RN), que liderou a rejei\u00e7\u00e3o e tentou impedir a aprova\u00e7\u00e3o da \u201cAposentadoria de 10%\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O deputado Andr\u00e9s Celis, que faz parte do setor solid\u00e1rio e liberal do mesmo partido, assegura que \u201cno RN v\u00e1rios mudaram, se voc\u00ea tivesse me perguntado h\u00e1 tr\u00eas anos quem me representava no campo liberal, eu teria citado um Andr\u00e9s Allamand, mas hoje em dia, mudou. Hoje, claramente quem me representa \u00e9 Mario Desbordes. Acredito que um dos seus grandes atributos \u00e9 que ele sabe ler bem e sabe captar de forma adequada o que est\u00e1 acontecendo, n\u00e3o por uma quest\u00e3o de oportunismo, mas por realismo, ele n\u00e3o se complica por ter que ceder\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro dessa direita mais social, ganha destaque um grupo de parlamentares que se identificam como feministas ou pr\u00f3-direitos das mulheres, embora n\u00e3o antipatriarcais. Nomes como o da senadora Marcela Sabat e os das deputadas Paulina Nu\u00f1ez, Erika Olivera e Ximena Ossand\u00f3n cumpriram um papel fundamental para a aprova\u00e7\u00e3o da hist\u00f3rica Lei de Paridade de G\u00eanero para a Conven\u00e7\u00e3o Constitucional. Em mat\u00e9ria de autodetermina\u00e7\u00e3o do corpo s\u00e3o menos liberais, n\u00e3o apoiam a Lei do Aborto, mas a deputada Erika Oliveira apoiou a lei de Educa\u00e7\u00e3o Sexual Integral.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dentro desse setor mais solid\u00e1rio incluem-se tamb\u00e9m alguns dirigentes da Uni\u00e3o Democrata Independente, principalmente prefeitos. O mais destacado \u00e9 Joaqu\u00edn Lav\u00edn, vereador da comuna elitista Las Condes e pr\u00e9-candidato presidencial da direita. Durante seu per\u00edodo como prefeito, imitou v\u00e1rias pol\u00edticas populares idealizadas pelo prefeito comunista Daniel Jadue, seu principal oponente para a pr\u00f3xima elei\u00e7\u00e3o presidencial. Joaqu\u00edn Lav\u00edn \u00e9 um hist\u00f3rico dirigente da UDI, que apoiou a ditadura militar de Augusto Pinochet, membro do seleto grupo dos \u2018Chicago Boys\u2019 e supranumer\u00e1rio do Opus Dei da Igreja Cat\u00f3lica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante sua carreira, demonstrou uma grande adaptabilidade para os momentos sociopol\u00edticos. No primeiro governo da presidenta socialista Michelle Bachelet, ele se declarou \u201caliancista-bachelista\u201d e declarou sua admira\u00e7\u00e3o pela lideran\u00e7a da mandat\u00e1ria. No meio da revolta social de 2019, apoiou a ideia de convocar um plebiscito para mudar a Constitui\u00e7\u00e3o idealizada por Jaime Guzm\u00e1n, com quem compartilhou fileiras no \u201cgremialismo\u201d, e foi partid\u00e1rio do \u201cAprovo\u201d. No meio da discuss\u00e3o constitucional, surpreendeu ao se denominar como \u201csocial-democrata\u201d ao estilo da direita alem\u00e3, o que gerou fortes cr\u00edticas nos setores mais duros de seu partido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O prefeito de Las Condes tem uma estrat\u00e9gia de comunica\u00e7\u00e3o potente, \u00e9 ativo nas redes sociais e sempre mant\u00e9m um tom amig\u00e1vel e n\u00e3o conflituoso, sua principal vitrine tem sido a televis\u00e3o aberta, h\u00e1 alguns anos se tornou painelista de \u201cBienvenidos\u201d, um dos programas matinais mais assistidos no Chile. Desde a revolta de 2019 se tornou um dos principais rostos dos programas matutinos que assumiram um papel l\u00fadico, informativo e pol\u00edtico, no que se chamou \u201ccelebritiza\u00e7\u00e3o ou matinaliza\u00e7\u00e3o da pol\u00edtica\u201d.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEm rela\u00e7\u00e3o a Lav\u00edn, acho que sempre cabe a d\u00favida de quanto suas viradas n\u00e3o s\u00e3o oportunistas e ele se mant\u00e9m sendo um chicago-gremialista ou est\u00e1 pensando sobre as quest\u00f5es politicamente. N\u00e3o sei se Lav\u00edn e seu entorno e forma\u00e7\u00e3o v\u00eam desse mundo, ele \u00e9 muito pr\u00f3ximo de Larroulet\u201d, aponta o acad\u00eamico Hugo Herrera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A historiadora Valentina Verbal garante que a direita sempre teve v\u00e1rias tend\u00eancias, principalmente liberais e conservadoras, \u201cem geral a tend\u00eancia social-crist\u00e3 sempre foi muito minorit\u00e1ria na direita (...) o social-crist\u00e3o n\u00e3o se refere aos conservadores defendendo a doutrina social da igreja, refere-se a uma tend\u00eancia dentro do cristianismo que se op\u00f5e ao capitalismo, \u00e9 como um anticapitalismo social-crist\u00e3o, \u00e9 como uma terceira via, uma alternativa ao socialismo e ao capitalismo. Como o que terminou sendo no final a Democracia Crist\u00e3; na direita houve essa tend\u00eancia, mas muito pequena, que no final foi o setor que se uniu \u00e0 falange nacional para formar a DC. <strong>No presente, a direita social-crist\u00e3 tem tentado de se reinstalar intelectualmente\u201d.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>\u201cO que \u00e9 chamado de direita social, acredito que, mais do que uma direita social, \u00e9 uma direita populista.<\/strong> No sentido de que entende que a direita tem que responder aos movimentos sociais, \u00e0 rua. Populismo que no fundo considera <strong>que a base da pol\u00edtica deve ser o povo acima da elite.<\/strong> Ou seja, as elites n\u00e3o podem trabalhar independentemente do povo, devem escutar. E foi nisso que caiu principalmente o Renova\u00e7\u00e3o Nacional, especialmente com Ossand\u00f3n, que agora \u00e9 investigado por fraude fiscal. E isso foi pego por Mario Desbordes e Lav\u00edn por outro lado. Qual \u00e9 o elemento ideol\u00f3gico que eles t\u00eam? Eles n\u00e3o t\u00eam um elemento ideol\u00f3gico de fundo, n\u00e3o \u00e9 que digam \u2018bom, n\u00f3s temos que nos mover de acordo com esses princ\u00edpios\u2019, eles n\u00e3o t\u00eam um projeto elaborado\u201d, acrescenta a intelectual liberal.<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\"><img decoding=\"async\" width=\"1024\" height=\"722\" src=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2-1024x722.jpg\" alt=\"\" class=\"wp-image-75\" srcset=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2-1024x722.jpg 1024w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2-300x212.jpg 300w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2-768x542.jpg 768w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2-1536x1083.jpg 1536w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2-1568x1106.jpg 1568w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/BANNER-CHILE2.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading\"><strong>A ultradireita populista<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O ressurgimento da direita dura ou radical em n\u00edvel global tamb\u00e9m tem sua express\u00e3o no Chile. Por fora da coaliz\u00e3o Chile Vamos, come\u00e7aram a surgir movimentos e partidos que se denominam \u201cA Direita\u201d, acusando a atual coaliz\u00e3o de governo de ser uma vers\u00e3o \u201clight\u201d que renunciou aos princ\u00edpios da direita tradicional. Seguem<strong>&nbsp;a receita dos movimentos ultraconservadores no mundo, identificam-se como republicanos, capitalistas e libert\u00e1rios economicamente, mas s\u00e3o extremamente conservadores do ponto de vista moral. Reivindicam o legado da ditadura de Augusto Pinochet e consagram a fam\u00edlia heteronormativa como o n\u00facleo da sociedade. Teorizam contra o que denominam \u201cideologia de g\u00eanero\u201d, dizem representar o \u201cChile real\u201d e renegam o mundo pol\u00edtico tradicional, que eles afirmam ter sido cooptado pela corrup\u00e7\u00e3o.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A refer\u00eancia com maior peso dessa direita dura \u00e9 o rec\u00e9m-fundado Partido Republicano, presidido por Jos\u00e9 Antonio Kast (JAK), ex-militante da Uni\u00e3o Democrata Independente. JAK cultiva o mesmo discurso \u201cantipol\u00edtico\u201d e <strong>antiestablishment\u201d que foi promovido por Donald Trump nos Estados Unidos e por Jair Bolsonaro no Brasil<\/strong>, apresentando-se como um outsider, apesar de sua carreira pol\u00edtica ser muito tradicional. Antes mesmo de se formar como advogado, foi eleito vereador da comuna de Buin; durante 19 anos foi deputado no Congresso Nacional e, apesar de ter liderado a bancada do seu ex-partido, nunca conseguiu se destacar como um rosto promissor na UDI. Em 2016, renunciou a seu partido e concorreu como independente para a presid\u00eancia, apoiado por um n\u00facleo de confian\u00e7a que depois daria vida ao movimento A\u00e7\u00e3o Republicana, base social do Partido Republicano. Na disputa para chegar ao pal\u00e1cio La Moneda, Kast conseguiu 8% das prefer\u00eancias, ganhando um espa\u00e7o no mapa pol\u00edtico do Chile.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O movimento A\u00e7\u00e3o Republicana tem sido um dos mais cr\u00edticos do presidente Sebasti\u00e1n Pi\u00f1era. Na minuta \u201cO Chile precisa de um projeto de direita\u201d, destacam que seu \u201cgoverno foi incapaz de baixar os impostos, proteger a fam\u00edlia, garantir a ordem p\u00fablica e o Estado de Direito\u201d. No entanto, no setor tamb\u00e9m prevalece o pragmatismo e que tudo fique em fam\u00edlia: apesar das cr\u00edticas ao presidente, ap\u00f3s sofrer a derrota no plebiscito constitucional, Jos\u00e9 Antonio Kast enviou uma carta a Sebasti\u00e1n Pi\u00f1era na qual pede que ele intervenha para que a direita entre em uma lista conjunta para disputar a elei\u00e7\u00e3o de delegados para a Conven\u00e7\u00e3o Constitucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No mundo da direita dura tamb\u00e9m h\u00e1 organiza\u00e7\u00f5es mais extremas, grupos de choque e de corte nacionalista. O \u201cMovimento Social Patriota\u201d e \u201cCapitalismo Revolucion\u00e1rio\u201d ou \u201cA Vanguarda\u201d s\u00e3o as que alcan\u00e7aram maior visibilidade. Foram parte importante das marchas organizadas pelo \u201cRejeito\u201d no plebiscito pela nova Constitui\u00e7\u00e3o. Foram \u00e0s manifesta\u00e7\u00f5es usando coletes \u00e0 prova de balas e capacetes, estavam armados com bast\u00f5es retr\u00e1teis, g\u00e1s de pimenta e escudos. Protagonizaram diferentes atos violentos contra pessoas que se manifestavam a favor do \u201cAprovo\u201d, e um de seus principais integrantes, Sebasti\u00e1n Izquierdo, est\u00e1 sendo processado pelo Minist\u00e9rio P\u00fablico por les\u00f5es e amea\u00e7as durante as marchas do Rejeito. Apesar de o restante da direita renegar esses grupos mais ultradireitistas, foi poss\u00edvel observar alguma proximidade com militantes da UDI, como com uma ex-candidata a deputada, Loreto Letelier, que apareceu em um v\u00eddeo agradecendo \u201cA Vanguarda\u201d por proteger as marchas do Rejeito.&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Embora o setor seja diverso quanto \u00e0 express\u00e3o de sua radicalidade, eles compartilham princ\u00edpios comuns como o de uma economia capitalista e libert\u00e1ria, acompanhada de um Estado pequeno, do papel subsidi\u00e1rio e focado na seguran\u00e7a policial.<\/strong> Prestam tributo a valores conservadores, principalmente crist\u00e3os, que os levaram a impulsionar movimentos \u201cantig\u00eanero\u201d. Aqui se encontram organiza\u00e7\u00f5es como \u201cSempre pela Vida\u201d ou \u201cO \u00f4nibus da Liberdade\u201d, que se organizaram contra a legaliza\u00e7\u00e3o do aborto, tamb\u00e9m h\u00e1 o movimento \u201cCom meus Filhos N\u00e3o se Meta\u201d, que surgiu como rea\u00e7\u00e3o \u00e0s reformas educacionais realizadas pelo governo de Michelle Bachelet. Os grupos antig\u00eanero t\u00eam uma influ\u00eancia em todos os partidos de centro-direita chileno, um exemplo disso \u00e9 o forte lobby que mobilizaram contra a Lei de Educa\u00e7\u00e3o Sexual Integral, proposta por um grupo de parlamentares de centro-esquerda, iniciativa que finalmente foi rejeitada no Congresso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cO movimento antig\u00eanero no Chile come\u00e7a h\u00e1 uns dez anos de forma mais sistem\u00e1tica e alcan\u00e7a seu auge com o \u00f4nibus da organiza\u00e7\u00e3o \u2013 espanhola de extrema direita \u2013 HazteOir. Tem liga\u00e7\u00f5es com certos l\u00edderes que, apesar de n\u00e3o participarem ativamente em partidos pol\u00edticos, recebem apoio de alguns dirigentes da UDI. Da mesma forma, um personagem importante que se vinculou ao financiamento \u00e9 Jos\u00e9 Antonio Kast. Al\u00e9m disso, as igrejas evang\u00e9licas t\u00eam desempenhado um papel importante, e mais recentemente com a bancada evang\u00e9lica do Congresso\u201d, explica Jaime Barriento, doutor em Psicologia Social e acad\u00eamico da Universidade Alberto Hurtado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O mundo evang\u00e9lico \u00e9 outro setor que flerta com a direita dura, mas, diferentemente do Brasil, onde se constitu\u00edram como uma for\u00e7a pol\u00edtica com representa\u00e7\u00e3o parlamentar coesa, no Chile n\u00e3o contam com uma articula\u00e7\u00e3o t\u00e3o clara e distribuem-se em diferentes partidos de centro-direita. O deputado do Renova\u00e7\u00e3o Nacional Leonidas Romero \u00e9 evang\u00e9lico, e garante que o voto de sua igreja foi fundamental para que o presidente Pi\u00f1era ganhasse as elei\u00e7\u00f5es, mas \u201cquando chegou a La Moneda, ele se esqueceu e come\u00e7ou a apoiar essas leis como o casamento homossexual\u201d, indica Romero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cInfelizmente, n\u00f3s do mundo crist\u00e3o, especialmente evang\u00e9lico, chegamos tarde na pol\u00edtica. Ainda h\u00e1 pastores evang\u00e9licos que dizem \u00e0 sua congrega\u00e7\u00e3o que n\u00e3o \u00e9 saud\u00e1vel participar da pol\u00edtica, que n\u00e3o se deve adorar a dois deuses, e entregamos aos ateus e aos agn\u00f3sticos a constru\u00e7\u00e3o de nosso pa\u00eds. Produto disso, hoje em dia temos leis t\u00e3o aberrantes como o aborto libre, casamento igualit\u00e1rio, ado\u00e7\u00e3o homoparental, queriam ter a Educa\u00e7\u00e3o Sexual Integral (ESI),<strong> que sexualiza nossas crian\u00e7as<\/strong>. \u00c9 importante que mais crist\u00e3os e, principalmente, evang\u00e9licos cheguem a ocupar os cargos p\u00fablicos\u201d, destaca o deputado Romero, que enfatiza que n\u00e3o \u00e9 de ultradireita.&nbsp;<\/p>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-large imagen-izquierda\"><img loading=\"lazy\" decoding=\"async\" width=\"273\" height=\"1024\" src=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/Enmascarar-grupo-2-e1614228646740-273x1024.png\" alt=\"\" class=\"wp-image-76\" srcset=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/Enmascarar-grupo-2-e1614228646740-273x1024.png 273w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/Enmascarar-grupo-2-e1614228646740-80x300.png 80w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/Enmascarar-grupo-2-e1614228646740-410x1536.png 410w, https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/Enmascarar-grupo-2-e1614228646740.png 418w\" sizes=\"(max-width: 273px) 100vw, 273px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Os jovens representam outro setor em que a direita dura come\u00e7ou a crescer. \u201c\u00c9 importante que a democracia volte \u00e0s casas de estudo que hoje s\u00e3o sequestradas pela esquerda ideol\u00f3gica\u201d, declarou Jos\u00e9 Antonio Kast, no \u00e2mbito de uma turn\u00ea nacional em universidades que realizou em 2018. <strong>Tentando ganhar a simpatia juvenil, JAK foi o primeiro pol\u00edtico em se aventurar no TikTok <\/strong>e fez at\u00e9 o desafio do reggaeton \u201cTusa\u201d, o hit do ver\u00e3o de 2020. Pouco a pouco, Kast foi montando uma rede de jovens profissionais, intelectuais e at\u00e9 youtubers que o convidam para seus programas, alcan\u00e7ando notoriedade nos ciberc\u00edrculos republicanos. Soma-se a isso uma esp\u00e9cie de polo te\u00f3rico desenvolvido em think tanks como o Centro de Estudos Libert\u00e1rios, onde a fil\u00f3sofa Vannessa Kaisser \u00e9 um dos principais quadros intelectuais e influencer em seu canal do YouTube, \u201cEsfera P\u00fablica\u201d, que tem milhares de visitas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na direita dura tamb\u00e9m usam a estrat\u00e9gia das <strong>fake news<\/strong>. Em 2019, criticaram Jos\u00e9 Antonio Kast por divulgar informa\u00e7\u00e3o falsa sobre a ex-presidenta Michelle Bachelet: \u201cFoi c\u00famplice do tr\u00e1fico de pessoas\u201d, disse em um canal de televis\u00e3o, fazendo alus\u00e3o \u00e0 grande quantidade de migrantes haitianos que chegaram ao Chile durante seu governo, informa\u00e7\u00e3o que foi desmentida posteriormente. Durante a campanha do Rejeito tamb\u00e9m tentaram implantar um discurso do terror, tentaram reviver o efeito do \u201cChilezuela\u201d, apontando que o Chile seria semelhante ao regime de Nicol\u00e1s Maduro se houvesse uma mudan\u00e7a constitucional. Dessa vez, a estrat\u00e9gia n\u00e3o rendeu os mesmos frutos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No \u00e2mbito comunicacional, a equipe do Partido Republicano desenvolveu uma pol\u00edtica de autonomia das m\u00eddias tradicionais, e as redes sociais t\u00eam sido suas principais plataformas. \u201cPotencializamos nossos pr\u00f3prios meios de comunica\u00e7\u00e3o\u201d, destacou a jornalista do Partido Republicano, Carolina Ayala, em uma entrevista ao jornal La Segunda, com o objetivo de que \u201cn\u00e3o existam deturpa\u00e7\u00f5es\u201d, explicou. Al\u00e9m disso, desenvolveu<strong> uma \u00e1gil rede de comunica\u00e7\u00e3o via WhatsApp<\/strong> atrav\u00e9s da qual coordenam os desdobramentos nas redes sociais e t\u00eam um grande poder de ocupa\u00e7\u00e3o marcando trending topic no Twitter. Asseguram que n\u00e3o trabalham com ag\u00eancias, mas nos \u00faltimos meses teriam contado com a assessoria de \u201cArtool\u201d, ag\u00eancia de Jorge Selume, o ex-chefe da Secretaria de Comunica\u00e7\u00f5es do governo de Sebasti\u00e1n Pi\u00f1era, que deixou o cargo ap\u00f3s apresentar um relat\u00f3rio de Big Data que apontava que houve influ\u00eancia \u201cestrangeira\u201d na<strong> revolta social de 2019 e que os e as fan\u00e1ticas do K-Pop estavam por tr\u00e1s das manifesta\u00e7\u00f5es.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo Cristi\u00e1n Leporati, analista especializado em comunica\u00e7\u00e3o pol\u00edtica, \u201cKast tem tentado replicar o que viu em outros lugares e n\u00e3o vai sair desse modelo, vai continuar crescendo em seu padr\u00e3o eleitoral, em seus seguidores, porque obviamente em um mundo de d\u00favidas o ser humano precisa de certezas. Vamos continuar vendo essa f\u00f3rmula, propagand\u00edstica e ret\u00f3rica, at\u00e9 que deixe de ser operativa e n\u00e3o permita sucessos eleitorais\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pol\u00edtica e estrat\u00e9gia comunicacional da direita dura tem forjado la\u00e7os com seus s\u00edmiles estrangeiros. Jos\u00e9 Antonio Kast se reuniu com diferentes l\u00edderes do setor. Em outubro de 2018, JAK chegou ao Brasil para se encontrar com o presidente Jair Bolsonaro e, em meados de 2019, Kast teve uma reuni\u00e3o com os l\u00edderes do partido espanhol Vox e seu l\u00edder, Santiago Abascal. No encontro, abordaram \u201ca urg\u00eancia de frear o marxismo cultural e a necessidade de defender valores conjuntos entre pa\u00edses irm\u00e3os\u201d, segundo detalhou o pol\u00edtico chileno. O que nunca ficou claro \u00e9 se o Partido Republicano foi assessorado pela<strong> plataforma \u201cThe Movement\u201d, que se oferece para movimentos de direita dura, criada pelo ide\u00f3logo e ex-assessor de Trump, Steve Bannon.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essas s\u00e3o as faces da direita chilena: solid\u00e1rios, economicistas e ultradireitistas, grupos que se encontram em um momento de mudan\u00e7a e acomoda\u00e7\u00e3o, e que durante o \u00faltimo ano desencadearam uma luta interna pela nova hegemonia no setor, luta intensificada pelo processo constituinte que foi aberto no pa\u00eds. Uma disputa que n\u00e3o s\u00f3 colocou em xeque o governo de Sebasti\u00e1n Pi\u00f1era, que teve que contornar uma esp\u00e9cie de \u201csemiparlamentarismo\u201d de fato em um pa\u00eds hiperpresidencialista, endossado por parlamentares de suas pr\u00f3prias fileiras; como tamb\u00e9m revelou que o mundo direitista chileno est\u00e1 fragmentado e em tens\u00e3o, no meio de uma profunda crise pol\u00edtica que atravessa o pa\u00eds. \u00c9 claro que, passados 30 anos ap\u00f3s a ditadura,<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u201cas direitas\u201d v\u00e3o al\u00e9m do projeto de \u201co\u00e1sis neoliberal\u201d deixado por Jaime Guzm\u00e1n.<\/strong><\/h2>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En Estado de shock, as\u00ed qued\u00f3 gran parte de la derecha chilena, En Estado de shock, as\u00ed qued\u00f3 gran parte de la derecha chilena, tras los resultados del plebiscito constitucional del 25 de octubre en Chile y que dio por ganadora la opci\u00f3n del \u201cApruebo\u201d a una Nueva Constituci\u00f3n, con un 78 por ciento de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"autor":[13],"class_list":["post-1652","post","type-post","status-publish","format-standard","hentry","category-sin-categoria","autor-macarena-segovia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chile - Peligro! Cruce a la derecha<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chile - Peligro! Cruce a la derecha\" \/>\n<meta property=\"og:description\" content=\"En Estado de shock, as\u00ed qued\u00f3 gran parte de la derecha chilena, En Estado de shock, as\u00ed qued\u00f3 gran parte de la derecha chilena, tras los resultados del plebiscito constitucional del 25 de octubre en Chile y que dio por ganadora la opci\u00f3n del \u201cApruebo\u201d a una Nueva Constituci\u00f3n, con un 78 por ciento de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jaqueala.com\/lasderechas\/pt\/chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Peligro! Cruce a la derecha\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-04T21:44:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-30T21:59:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"26 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/#\\\/schema\\\/person\\\/9db9ac3e9aa1d7ef3b2befa9d229250b\"},\"headline\":\"Chile\",\"datePublished\":\"2022-03-04T21:44:55+00:00\",\"dateModified\":\"2022-03-30T21:59:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/\"},\"wordCount\":5865,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/COLLAGE1.png\",\"articleSection\":[\"Sin categor\u00eda\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/\",\"url\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/\",\"name\":\"Chile - Peligro! Cruce a la derecha\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/COLLAGE1.png\",\"datePublished\":\"2022-03-04T21:44:55+00:00\",\"dateModified\":\"2022-03-30T21:59:38+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/#\\\/schema\\\/person\\\/9db9ac3e9aa1d7ef3b2befa9d229250b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/COLLAGE1.png\",\"contentUrl\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/COLLAGE1.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/#website\",\"url\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/\",\"name\":\"Peligro! Cruce a la derecha\",\"description\":\"Un especial period\u00edstico que investiga la derecha en seis pa\u00edses de Am\u00e9rica Latina (Chile, Argentina, Brasil, Colombia, Rep\u00fablica Dominicana, M\u00e9xico).  No es un ensayo pol\u00edtico ni acad\u00e9mico sino que est\u00e1 basado en reporter\u00eda a referentes de la derecha y a analistas pol\u00edticos.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/#\\\/schema\\\/person\\\/9db9ac3e9aa1d7ef3b2befa9d229250b\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f07934d51d57d103818da7c6352cbaad59c8e3eec98ca0a27dccf4c042ce09?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f07934d51d57d103818da7c6352cbaad59c8e3eec98ca0a27dccf4c042ce09?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a8f07934d51d57d103818da7c6352cbaad59c8e3eec98ca0a27dccf4c042ce09?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"sameAs\":[\"https:\\\/\\\/desdeelaltillo.com\\\/las-derechas\"],\"url\":\"https:\\\/\\\/jaqueala.com\\\/lasderechas\\\/pt\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chile - Peligro! Cruce a la derecha","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"pt_BR","og_type":"article","og_title":"Chile - Peligro! Cruce a la derecha","og_description":"En Estado de shock, as\u00ed qued\u00f3 gran parte de la derecha chilena, En Estado de shock, as\u00ed qued\u00f3 gran parte de la derecha chilena, tras los resultados del plebiscito constitucional del 25 de octubre en Chile y que dio por ganadora la opci\u00f3n del \u201cApruebo\u201d a una Nueva Constituci\u00f3n, con un 78 por ciento de [&hellip;]","og_url":"https:\/\/jaqueala.com\/lasderechas\/pt\/chile\/","og_site_name":"Peligro! Cruce a la derecha","article_published_time":"2022-03-04T21:44:55+00:00","article_modified_time":"2022-03-30T21:59:38+00:00","og_image":[{"url":"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png","type":"","width":"","height":""}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Admin","Est. tempo de leitura":"26 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#article","isPartOf":{"@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/"},"author":{"name":"Admin","@id":"https:\/\/jaqueala.com\/lasderechas\/#\/schema\/person\/9db9ac3e9aa1d7ef3b2befa9d229250b"},"headline":"Chile","datePublished":"2022-03-04T21:44:55+00:00","dateModified":"2022-03-30T21:59:38+00:00","mainEntityOfPage":{"@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/"},"wordCount":5865,"commentCount":0,"image":{"@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#primaryimage"},"thumbnailUrl":"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png","articleSection":["Sin categor\u00eda"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jaqueala.com\/lasderechas\/chile\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/","url":"https:\/\/jaqueala.com\/lasderechas\/chile\/","name":"Chile - Peligro! Cruce a la derecha","isPartOf":{"@id":"https:\/\/jaqueala.com\/lasderechas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#primaryimage"},"image":{"@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#primaryimage"},"thumbnailUrl":"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png","datePublished":"2022-03-04T21:44:55+00:00","dateModified":"2022-03-30T21:59:38+00:00","author":{"@id":"https:\/\/jaqueala.com\/lasderechas\/#\/schema\/person\/9db9ac3e9aa1d7ef3b2befa9d229250b"},"breadcrumb":{"@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jaqueala.com\/lasderechas\/chile\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#primaryimage","url":"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png","contentUrl":"https:\/\/jaqueala.com\/lasderechas\/wp-content\/uploads\/2021\/02\/COLLAGE1.png"},{"@type":"BreadcrumbList","@id":"https:\/\/jaqueala.com\/lasderechas\/chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jaqueala.com\/lasderechas\/"},{"@type":"ListItem","position":2,"name":"Chile"}]},{"@type":"WebSite","@id":"https:\/\/jaqueala.com\/lasderechas\/#website","url":"https:\/\/jaqueala.com\/lasderechas\/","name":"Peligro! Cruce a la derecha","description":"Un especial period\u00edstico que investiga la derecha en seis pa\u00edses de Am\u00e9rica Latina (Chile, Argentina, Brasil, Colombia, Rep\u00fablica Dominicana, M\u00e9xico).  No es un ensayo pol\u00edtico ni acad\u00e9mico sino que est\u00e1 basado en reporter\u00eda a referentes de la derecha y a analistas pol\u00edticos.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jaqueala.com\/lasderechas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/jaqueala.com\/lasderechas\/#\/schema\/person\/9db9ac3e9aa1d7ef3b2befa9d229250b","name":"Admin","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/a8f07934d51d57d103818da7c6352cbaad59c8e3eec98ca0a27dccf4c042ce09?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a8f07934d51d57d103818da7c6352cbaad59c8e3eec98ca0a27dccf4c042ce09?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a8f07934d51d57d103818da7c6352cbaad59c8e3eec98ca0a27dccf4c042ce09?s=96&d=mm&r=g","caption":"Admin"},"sameAs":["https:\/\/desdeelaltillo.com\/las-derechas"],"url":"https:\/\/jaqueala.com\/lasderechas\/pt\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/posts\/1652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/comments?post=1652"}],"version-history":[{"count":3,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/posts\/1652\/revisions"}],"predecessor-version":[{"id":2816,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/posts\/1652\/revisions\/2816"}],"wp:attachment":[{"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/media?parent=1652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/categories?post=1652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/tags?post=1652"},{"taxonomy":"autor","embeddable":true,"href":"https:\/\/jaqueala.com\/lasderechas\/pt\/wp-json\/wp\/v2\/autor?post=1652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}